{"id":9,"date":"2026-01-13T06:27:15","date_gmt":"2026-01-13T06:27:15","guid":{"rendered":"https:\/\/wp-4.designtocodes.com\/drivlex\/?page_id=9"},"modified":"2026-02-10T07:31:16","modified_gmt":"2026-02-10T07:31:16","slug":"home","status":"publish","type":"page","link":"https:\/\/wp-4.designtocodes.com\/drivlex\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b4e4ef e-flex e-con-boxed e-con e-parent\" data-id=\"3b4e4ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c3e54f e-con-full e-flex e-con e-child\" data-id=\"4c3e54f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bdf8161 e-con-full cart-2 e-flex e-con e-child\" data-id=\"bdf8161\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebd98b6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ebd98b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Drive Your\nDeal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6f06e2 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e6f06e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Explore thousands of verified car listings or post your own in just a few clicks.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6484f0a home-button elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6484f0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-car\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Explore Our Collection<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22d612c e-con-full e-flex e-con e-child\" data-id=\"22d612c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ff73875 e-con-full cart-2 e-flex elementor-invisible e-con e-child\" data-id=\"ff73875\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4324952 elementor-widget__width-inherit elementor-widget elementor-widget-icon-box\" data-id=\"4324952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVerified Buyers\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEvery buyer on Drivlex goes through an authenticity check for safer transactions.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-360ebc6 e-con-full cart-2 e-flex elementor-invisible e-con e-child\" data-id=\"360ebc6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3e46b7 elementor-widget__width-initial elementor-widget elementor-widget-icon-box\" data-id=\"b3e46b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZero Hidden Fees\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCreate your listing for free no commissions or hidden \ncharges.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9a0c3e e-con-full cart-2 e-flex elementor-invisible e-con e-child\" data-id=\"e9a0c3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d234472 elementor-widget__width-initial elementor-widget elementor-widget-icon-box\" data-id=\"d234472\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInstant Visibility\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYour listing reaches thousands of active buyers in \nminutes.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9241fd1 e-con-full cart-2 e-flex elementor-invisible e-con e-child\" data-id=\"9241fd1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb18d14 elementor-widget__width-initial elementor-widget elementor-widget-icon-box\" data-id=\"fb18d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSupport That Cares\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOur expert support team is here to help you close deals \nfaster.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3af1dac e-flex e-con-boxed e-con e-parent\" data-id=\"3af1dac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-493418f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"493418f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Explore Our Premium Brands<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c66ec72 e-con-full e-flex e-con e-child\" data-id=\"c66ec72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3394b3e e-con-full e-flex e-con e-child\" data-id=\"3394b3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-dc8038f e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"dc8038f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a04329f elementor-widget elementor-widget-heading\" data-id=\"a04329f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Audi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cae73a8 e-con-full e-flex e-con e-child\" data-id=\"cae73a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0952c41 e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"0952c41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70a3496 elementor-widget elementor-widget-heading\" data-id=\"70a3496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">BMW<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-815edb3 e-con-full e-flex e-con e-child\" data-id=\"815edb3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-cb46f95 e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"cb46f95\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b7015 elementor-widget elementor-widget-heading\" data-id=\"e0b7015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ford<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5bbed9 e-con-full e-flex e-con e-child\" data-id=\"c5bbed9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c4958fb e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"c4958fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8425250 elementor-widget elementor-widget-heading\" data-id=\"8425250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mercedes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-696751d e-con-full e-flex e-con e-child\" data-id=\"696751d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4acaeb3 e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"4acaeb3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-380c8c3 elementor-widget elementor-widget-heading\" data-id=\"380c8c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Peugeot<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-efce4e9 e-con-full e-flex e-con e-child\" data-id=\"efce4e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4397fe6 e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"4397fe6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bef726 elementor-widget elementor-widget-heading\" data-id=\"9bef726\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Volkswagen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c907d6 e-con-full e-flex e-con e-child\" data-id=\"5c907d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f65e49b e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"f65e49b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f97ed0a elementor-widget elementor-widget-heading\" data-id=\"f97ed0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Bentley<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74adbc6 e-con-full e-flex e-con e-child\" data-id=\"74adbc6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bc593ae e-con-full animated-border-1 e-flex e-con e-child\" data-id=\"bc593ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5e01ed elementor-widget elementor-widget-heading\" data-id=\"a5e01ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nissan<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6122bca e-flex e-con-boxed e-con e-parent\" data-id=\"6122bca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98cc485 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"98cc485\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Brows Categories<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7236642 e-con-full e-flex e-con e-child\" data-id=\"7236642\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-071495d e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"071495d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3450963 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3450963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"67\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-1.svg\" class=\"attachment-full size-full wp-image-178\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">suv<\/h3><p class=\"elementor-image-box-description\">Spacious, powerful, and built for every road.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffed030 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"ffed030\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-013df6b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"013df6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"76\" height=\"33\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-2.svg\" class=\"attachment-full size-full wp-image-179\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sedan<\/h3><p class=\"elementor-image-box-description\">Comfortable rides with style and efficiency.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b6b5d1 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"0b6b5d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d886bea elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d886bea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"69\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-3.svg\" class=\"attachment-full size-full wp-image-180\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hatchback<\/h3><p class=\"elementor-image-box-description\">Compact, affordable, and perfect for city driving.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-726b9ca e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"726b9ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e81282c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e81282c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"83\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-4.svg\" class=\"attachment-full size-full wp-image-181\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Electric<\/h3><p class=\"elementor-image-box-description\">Eco-friendly innovation with zero emissions.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8145c20 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"8145c20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc539e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1cc539e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-6.svg\" class=\"attachment-full size-full wp-image-183\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Coupe<\/h3><p class=\"elementor-image-box-description\">Sporty two-door design with sleek performance.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b06926 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"3b06926\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc9f20b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cc9f20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-5.svg\" class=\"attachment-full size-full wp-image-182\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hybrid<\/h3><p class=\"elementor-image-box-description\">Efficient driving powered by both fuel and electric energy.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66be404 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"66be404\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf2880 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"eaf2880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"59\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-8.svg\" class=\"attachment-full size-full wp-image-185\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Convertible<\/h3><p class=\"elementor-image-box-description\">Open-top freedom for an unforgettable driving experience.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8191cb0 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"8191cb0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b65f02 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7b65f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"85\" height=\"37\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/categories-icon-7.svg\" class=\"attachment-full size-full wp-image-184\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Van<\/h3><p class=\"elementor-image-box-description\">Spacious and practical for families or business use.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-064111b e-flex e-con-boxed e-con e-parent\" data-id=\"064111b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff28d66 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ff28d66\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">We're big on<br>\nwhat matters to you<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92aad2a e-con-full e-flex e-con e-child\" data-id=\"92aad2a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25659ef e-con-full header-section e-flex elementor-invisible e-con e-child\" data-id=\"25659ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6107466 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6107466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"38\" height=\"50\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/features-icon-1.svg\" class=\"attachment-full size-full wp-image-211\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Secure<br>Communication<\/h3><p class=\"elementor-image-box-description\">Connect with buyers or sellers directly through our built-in chat system .<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f686bee e-con-full header-section e-flex elementor-invisible e-con e-child\" data-id=\"f686bee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c09ad87 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c09ad87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"29\" height=\"50\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/features-icon-2.svg\" class=\"attachment-full size-full wp-image-212\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Fast &amp; Easy <br>Posting<\/h3><p class=\"elementor-image-box-description\">List your car in just minutes. Upload photos, add details, and reach thousands of potential buyers instantly.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3098d00 e-con-full header-section e-flex elementor-invisible e-con e-child\" data-id=\"3098d00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6d7d8 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9a6d7d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"50\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/features-icon-3.svg\" class=\"attachment-full size-full wp-image-213\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Verified Sellers &amp; <br>Listings<\/h3><p class=\"elementor-image-box-description\">Every car listing is reviewed and verified to ensure genuine sellers and authentic details no scams, no surprises.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a726bbc e-con-full header-section e-flex elementor-invisible e-con e-child\" data-id=\"a726bbc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d47305a elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d47305a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/features-icon-4.svg\" class=\"attachment-full size-full wp-image-214\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Best Deals, Real <br>Value<\/h3><p class=\"elementor-image-box-description\">Find cars that fit your budget perfectly with transparent pricing and zero hidden costs.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59abb50 e-flex e-con-boxed e-con e-parent\" data-id=\"59abb50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-884e74c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"884e74c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Explore All Vehicles<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8831c8b e-con-full e-flex e-con e-child\" data-id=\"8831c8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cfeb553 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"cfeb553\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b8e899 elementor-widget elementor-widget-image\" data-id=\"9b8e899\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-1.jpg\" class=\"attachment-large size-large wp-image-242\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-1.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-1-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58f0d01 e-con-full e-flex e-con e-child\" data-id=\"58f0d01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-af4d24d e-con-full e-flex e-con e-child\" data-id=\"af4d24d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85045ce elementor-widget elementor-widget-heading\" data-id=\"85045ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">Toyota Camry New<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6a4e7b elementor-widget elementor-widget-text-editor\" data-id=\"f6a4e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d08e2b4 e-con-full e-flex e-con e-child\" data-id=\"d08e2b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7c0e7 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1f7c0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21b009d elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"21b009d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-977cf35 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"977cf35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa4dec3 e-con-full e-flex e-con e-child\" data-id=\"aa4dec3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa26c2 elementor-widget elementor-widget-heading\" data-id=\"2fa26c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$40,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3601176 elementor-widget elementor-widget-button\" data-id=\"3601176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fda72f e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"2fda72f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2a82ed elementor-widget elementor-widget-image\" data-id=\"f2a82ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-2.jpg\" class=\"attachment-large size-large wp-image-430\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-2.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-2-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c83fd2 e-con-full e-flex e-con e-child\" data-id=\"4c83fd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3258391 e-con-full e-flex e-con e-child\" data-id=\"3258391\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e66108 elementor-widget elementor-widget-heading\" data-id=\"3e66108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">T-Cross \u2013 2023<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faf9d1e elementor-widget elementor-widget-text-editor\" data-id=\"faf9d1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38344bf e-con-full e-flex e-con e-child\" data-id=\"38344bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06747b8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"06747b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13071c5 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"13071c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49e1a6b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"49e1a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd743b2 e-con-full e-flex e-con e-child\" data-id=\"cd743b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8af1041 elementor-widget elementor-widget-heading\" data-id=\"8af1041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$40,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb1d7ff elementor-widget elementor-widget-button\" data-id=\"bb1d7ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-928a596 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"928a596\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0ad4a elementor-widget elementor-widget-image\" data-id=\"5b0ad4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-3.jpg\" class=\"attachment-large size-large wp-image-431\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-3.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-3-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-179509b e-con-full e-flex e-con e-child\" data-id=\"179509b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-77e71c7 e-con-full e-flex e-con e-child\" data-id=\"77e71c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-575eba6 elementor-widget elementor-widget-heading\" data-id=\"575eba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">C-Class \u2013 2023<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce114dd elementor-widget elementor-widget-text-editor\" data-id=\"ce114dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b5dff4 e-con-full e-flex e-con e-child\" data-id=\"3b5dff4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ee844 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d6ee844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf3aaea elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bf3aaea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fce4ad2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fce4ad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-764d306 e-con-full e-flex e-con e-child\" data-id=\"764d306\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13c35d3 elementor-widget elementor-widget-heading\" data-id=\"13c35d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$40,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b97b05b elementor-widget elementor-widget-button\" data-id=\"b97b05b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee54f7f e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"ee54f7f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e88b59 elementor-widget elementor-widget-image\" data-id=\"8e88b59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-4.jpg\" class=\"attachment-large size-large wp-image-432\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-4.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-4-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b59db7a e-con-full e-flex e-con e-child\" data-id=\"b59db7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6c62e6a e-con-full e-flex e-con e-child\" data-id=\"6c62e6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06b3e5b elementor-widget elementor-widget-heading\" data-id=\"06b3e5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">Ford Transit \u2013 2021<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-967fb5f elementor-widget elementor-widget-text-editor\" data-id=\"967fb5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8aef47 e-con-full e-flex e-con e-child\" data-id=\"a8aef47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8594dd7 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8594dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-854ce55 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"854ce55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aed2a75 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"aed2a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4864bcc e-con-full e-flex e-con e-child\" data-id=\"4864bcc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-164d7fe elementor-widget elementor-widget-heading\" data-id=\"164d7fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$22,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5906b20 elementor-widget elementor-widget-button\" data-id=\"5906b20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-361df25 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"361df25\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc1871 elementor-widget elementor-widget-image\" data-id=\"fbc1871\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-5.jpg\" class=\"attachment-large size-large wp-image-433\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-5.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-5-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9de704a e-con-full e-flex e-con e-child\" data-id=\"9de704a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-208dc88 e-con-full e-flex e-con e-child\" data-id=\"208dc88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e839e0a elementor-widget elementor-widget-heading\" data-id=\"e839e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">New GLC \u2013 2023<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01f2eb9 elementor-widget elementor-widget-text-editor\" data-id=\"01f2eb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4d4803 e-con-full e-flex e-con e-child\" data-id=\"f4d4803\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd61189 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bd61189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d93b7dc elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d93b7dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e06863 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7e06863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72e963a e-con-full e-flex e-con e-child\" data-id=\"72e963a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0df7b80 elementor-widget elementor-widget-heading\" data-id=\"0df7b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$95,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a524a6 elementor-widget elementor-widget-button\" data-id=\"4a524a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90105c5 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"90105c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-949c47e elementor-widget elementor-widget-image\" data-id=\"949c47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-6.jpg\" class=\"attachment-large size-large wp-image-434\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-6.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-6-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f3dc63 e-con-full e-flex e-con e-child\" data-id=\"1f3dc63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4d37cd8 e-con-full e-flex e-con e-child\" data-id=\"4d37cd8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69a7267 elementor-widget elementor-widget-heading\" data-id=\"69a7267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">Audi A6 3.5 \u2013 New<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35edba2 elementor-widget elementor-widget-text-editor\" data-id=\"35edba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d817dd0 e-con-full e-flex e-con e-child\" data-id=\"d817dd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bac3ee elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9bac3ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d03c27 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7d03c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b17baea elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b17baea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9df5aea e-con-full e-flex e-con e-child\" data-id=\"9df5aea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3c23d9 elementor-widget elementor-widget-heading\" data-id=\"e3c23d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$58,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5dde39 elementor-widget elementor-widget-button\" data-id=\"b5dde39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd1f0fa e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"dd1f0fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b52d33a elementor-widget elementor-widget-image\" data-id=\"b52d33a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-7.jpg\" class=\"attachment-large size-large wp-image-435\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-7.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-7-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddcdc76 e-con-full e-flex e-con e-child\" data-id=\"ddcdc76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d4a63d7 e-con-full e-flex e-con e-child\" data-id=\"d4a63d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1bfaf7 elementor-widget elementor-widget-heading\" data-id=\"b1bfaf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">Corolla Altis \u2013 2023<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9a6933 elementor-widget elementor-widget-text-editor\" data-id=\"f9a6933\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3988b6e e-con-full e-flex e-con e-child\" data-id=\"3988b6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8d63ed elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a8d63ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12b3bf0 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"12b3bf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-666617b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"666617b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cbb97f e-con-full e-flex e-con e-child\" data-id=\"8cbb97f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84b7c8d elementor-widget elementor-widget-heading\" data-id=\"84b7c8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$45,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1380d83 elementor-widget elementor-widget-button\" data-id=\"1380d83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a3998e e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"2a3998e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4627824 elementor-widget elementor-widget-image\" data-id=\"4627824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"192\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-8.jpg\" class=\"attachment-large size-large wp-image-436\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-8.jpg 302w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Car-8-300x191.jpg 300w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f12cf73 e-con-full e-flex e-con e-child\" data-id=\"f12cf73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-17bf114 e-con-full e-flex e-con e-child\" data-id=\"17bf114\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a52ded elementor-widget elementor-widget-heading\" data-id=\"8a52ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/drivlex\/buy-cars-single\/\">Ford Explorer 2023<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-772bfdd elementor-widget elementor-widget-text-editor\" data-id=\"772bfdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>3.5 D5 PowerPulse Momentum 5dr AW\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0107e3 e-con-full e-flex e-con e-child\" data-id=\"e0107e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-815c0a2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"815c0a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"15\" viewBox=\"0 0 19 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.94888 0.0277823C7.50686 0.134065 6.20447 0.517522 4.96819 1.19987L4.56707 1.42121L4.58728 1.4754C4.6066 1.52726 5.71738 3.51694 5.74349 3.54648C5.75047 3.55438 6.01135 3.42974 6.32331 3.26957C7.18118 2.82902 7.91072 2.61077 8.84688 2.5146L9.28268 2.46984V1.23601V0.00213709L9.19923 0.0088155C9.15331 0.0124791 9.04067 0.0209894 8.94888 0.0277823ZM9.72775 1.23494V2.46984L10.1635 2.51457C11.0901 2.6097 11.8585 2.83963 12.7044 3.27491C13.0079 3.43108 13.2615 3.55285 13.268 3.54553C13.2745 3.53816 13.5427 3.06311 13.864 2.48984C14.1961 1.89721 14.434 1.43361 14.4153 1.41529C14.3364 1.33813 13.4194 0.869151 13.0461 0.715051C12.0946 0.322282 11.2587 0.133416 9.9781 0.0218289L9.72775 0V1.23494ZM3.77388 1.9943C2.99119 2.59532 1.97462 3.73546 1.46702 4.58164C1.23143 4.97437 1.00404 5.38805 1.0178 5.39896C1.08133 5.44949 3.05506 6.60417 3.07757 6.60398C3.09397 6.60387 3.16981 6.48572 3.24618 6.34146C3.72581 5.43522 4.32169 4.70311 5.09162 4.07415C5.24461 3.94917 5.37457 3.83434 5.38039 3.819C5.39178 3.789 4.29565 1.80844 4.22381 1.72926L4.18082 1.68182L3.77388 1.9943ZM14.7577 1.76589C14.6232 1.9809 13.6221 3.78957 13.6221 3.81766C13.6221 3.83491 13.6706 3.88078 13.7299 3.91959C13.9645 4.07301 14.466 4.54374 14.7807 4.90602C15.1279 5.30573 15.5126 5.86603 15.758 6.32971C15.8378 6.48041 15.9163 6.60387 15.9326 6.60398C15.9488 6.60414 16.3494 6.37447 16.8227 6.09367C17.2961 5.81284 17.7501 5.54356 17.8317 5.49525C17.9133 5.44693 17.9855 5.40347 17.9922 5.39862C18.0122 5.38416 17.6681 4.77848 17.4305 4.40991C16.8005 3.43268 15.8929 2.45877 15.0353 1.83978L14.8122 1.67881L14.7577 1.76589ZM0.76982 5.94453C0.470697 6.68119 0.215932 7.61933 0.103553 8.39789C0.0682438 8.64243 0.0313031 9.19583 0.0201022 9.64771L0 10.4587H1.21062H2.42121V9.85661C2.42121 8.9351 2.52235 8.26581 2.78309 7.4621L2.92354 7.02915L2.3293 6.67683C2.00247 6.48305 1.54005 6.20713 1.30168 6.06368C1.06331 5.92023 0.859056 5.80284 0.847818 5.80284C0.83658 5.80284 0.801494 5.86661 0.76982 5.94453ZM17.1078 6.41992L16.0872 7.03022L16.2275 7.4626C16.4881 8.26577 16.5892 8.93533 16.5892 9.85661V10.4587H17.7946H19L19 9.89577C18.9999 8.92346 18.8891 8.05919 18.6502 7.16703C18.509 6.63997 18.2163 5.83089 18.162 5.81776C18.1435 5.81329 17.6691 6.08429 17.1078 6.41992ZM12.8618 8.0129C11.4542 8.48967 10.2789 8.88824 10.2499 8.89858C10.2177 8.9101 10.2822 8.96685 10.4153 9.04417C10.8789 9.31333 11.2331 9.83661 11.323 10.3849C11.3478 10.5361 11.3594 10.7263 11.3488 10.8074L11.3296 10.9548L11.3725 10.9279C11.409 10.9049 15.2114 7.41154 15.4199 7.20943C15.4601 7.17043 15.4768 7.14024 15.457 7.1423C15.4372 7.14436 14.2693 7.53614 12.8618 8.0129ZM9.03129 9.3105C8.60109 9.4746 8.23083 9.88603 8.13206 10.3098C8.10651 10.4192 8.09401 10.6341 8.10343 10.8016L8.12016 11.0989L8.22631 11.3221C8.3622 11.608 8.61222 11.8643 8.89372 12.0065L9.11578 12.1187H9.50521H9.89465L10.1074 12.0162C10.3788 11.8853 10.6479 11.6083 10.787 11.3168L10.896 11.0883V10.6876V10.2869L10.7904 10.0655C10.6548 9.78143 10.3825 9.5022 10.1097 9.36763L9.89465 9.26154L9.56084 9.24868L9.22704 9.23586L9.03129 9.3105ZM0.101846 11.136C0.186446 11.8561 0.483492 12.9292 0.817553 13.7216C1.01765 14.1961 1.44577 15 1.49843 15C1.55496 15 3.53388 13.8116 3.53388 13.7777C3.53388 13.7606 3.42602 13.5435 3.29421 13.2952C2.9287 12.6068 2.67953 11.9006 2.53236 11.136L2.49012 10.9166H1.28309H0.0760696L0.101846 11.136ZM16.4781 11.136C16.3165 11.9756 16.0339 12.7479 15.6204 13.4801C15.5413 13.6202 15.4765 13.7517 15.4765 13.7723C15.4765 13.8089 17.456 15 17.5169 15C17.5668 15 18.0181 14.1358 18.2161 13.661C18.539 12.8868 18.8257 11.8413 18.9086 11.136L18.9344 10.9166H17.7273H16.5203L16.4781 11.136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t20 Miles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e41403 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7e41403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.32166 0.0318865C1.78189 0.0999079 1.08678 0.307656 0.62045 0.540322C0.298096 0.701148 0.0660912 0.8602 0.0259022 0.947881C-0.0481427 1.10941 0.0115849 1.18587 0.538186 1.60385L1.04397 2.00528H1.14139C1.19499 2.00528 1.32708 1.95326 1.43494 1.88973C1.70616 1.72994 2.18304 1.57856 2.54285 1.53804C3.00996 1.48542 3.56954 1.56814 3.98642 1.75144L4.16352 1.82931L4.53064 1.42711C4.73256 1.2059 4.98515 0.949321 5.09197 0.856984C5.19876 0.764615 5.28615 0.67536 5.28615 0.658614C5.28615 0.607138 4.5453 0.272021 4.23547 0.183369C3.64952 0.0157102 2.91264 -0.0426322 2.32166 0.0318865ZM9.71604 0.894796C9.56781 0.948651 9.02972 1.15272 8.5203 1.34827C8.01085 1.54383 7.55752 1.70385 7.51292 1.70385H7.4318L7.05797 1.33742C6.5597 0.848946 6.344 0.758787 5.94696 0.872926L5.8083 0.912815L5.21187 1.49741C4.88382 1.81893 4.58946 2.13633 4.55769 2.20274C4.52596 2.26912 4.49301 2.39532 4.48449 2.48313C4.45916 2.74387 4.54735 2.91233 4.90703 3.29008C5.08167 3.47351 5.23841 3.65986 5.25536 3.70414C5.2723 3.74844 5.28615 4.13095 5.28615 4.55415V5.32362L5.35683 5.46462C5.44637 5.64316 9.34514 9.53873 9.56444 9.66871L9.71604 9.75857H9.95185H10.1877L10.3393 9.66888C10.4229 9.61938 11.2179 8.8541 12.1135 7.96081L13.7363 6.34243L13.7922 6.14862C13.8552 5.93082 13.8388 5.74528 13.74 5.55538C13.7064 5.49091 13.2519 5.01617 12.73 4.5004C12.2081 3.98463 11.7611 3.51729 11.7368 3.46182L11.6926 3.36101L11.792 2.97737L11.8913 2.59372L11.8555 2.42757C11.8358 2.33621 11.7906 2.2151 11.7552 2.15847C11.6579 2.00313 10.5747 0.94989 10.4449 0.884548C10.3826 0.853133 10.2538 0.820579 10.1586 0.812173L9.98554 0.796901L9.71604 0.894796ZM0.986598 3.98965C0.523565 4.47437 0.267811 4.95441 0.241636 5.38792L0.226443 5.63911L0.302307 5.83902C0.572412 6.55092 1.54817 6.76426 2.08494 6.2288C2.64095 5.67414 2.48447 4.85012 1.65772 3.9788L1.43764 3.74684H1.32809H1.21854L0.986598 3.98965ZM7.43719 4.20584C7.1622 4.4719 7.11564 4.55415 7.15401 4.70617C7.17702 4.79737 7.56129 5.22047 7.62109 5.22047C7.63951 5.22047 7.73502 5.14484 7.83335 5.0524C7.93165 4.95997 8.08469 4.85196 8.17346 4.81234L8.33486 4.74036L8.6218 4.73758L8.90875 4.73484L9.12712 4.84198L9.34548 4.94915L9.97711 5.5808L10.6088 6.21249V6.3007C10.6088 6.34923 10.5732 6.42998 10.5299 6.48012L10.451 6.57128H10.3421H10.2332L9.62094 5.96616C9.28417 5.63335 8.96009 5.33695 8.9008 5.30751C8.76821 5.24167 8.52098 5.23828 8.37589 5.30031C8.31626 5.3258 8.20725 5.40899 8.13364 5.48518L7.9998 5.62374L8.95885 6.57764C9.48636 7.10232 9.96667 7.55459 10.0262 7.58269C10.0861 7.61093 10.1706 7.62479 10.2151 7.61367C10.2594 7.60262 10.6011 7.2886 10.9744 6.91591L11.6531 6.23824V6.12347V6.00872L10.6166 4.97825L9.58007 3.94779H8.64198H7.70389L7.43719 4.20584ZM2.80986 7.27182C2.53214 7.55496 2.28167 7.91747 2.14895 8.22831L2.03896 8.48589L2.03808 8.75382L2.03721 9.02176L2.12658 9.21333C2.30889 9.60414 2.68909 9.8485 3.11722 9.84997C3.4135 9.85098 3.63719 9.76594 3.85238 9.57042C4.25649 9.20321 4.32795 8.70781 4.05821 8.14314C3.91174 7.83646 3.70261 7.53925 3.44086 7.2658L3.24628 7.0625H3.1307H3.01515L2.80986 7.27182ZM12.2168 8.59531L10.9785 9.82669L11.1895 10.034C11.3055 10.148 11.4597 10.2658 11.5321 10.2957C11.7207 10.3735 12.0202 10.3646 12.1984 10.2757C12.3812 10.1846 13.8192 8.77362 13.9202 8.58637L13.9923 8.4524L13.9924 8.21796C13.9925 8.05569 13.9736 7.94745 13.9309 7.8663C13.8742 7.75842 13.5147 7.36392 13.4731 7.36392C13.4631 7.36392 12.8978 7.91804 12.2168 8.59531ZM13.4772 9.81896L12.9263 10.369L13.066 10.5723C13.3396 10.9709 13.4644 11.4244 13.4267 11.883C13.3982 12.2298 13.3696 12.3098 12.9036 13.3458C12.679 13.8451 12.4952 14.2826 12.4952 14.3179C12.4952 14.3533 12.517 14.4132 12.5437 14.451C12.5969 14.5266 13.6252 15 13.7361 15C13.7742 15 13.8421 14.9661 13.887 14.9246C14.007 14.8139 14.7991 13.016 14.9088 12.6054L14.9982 12.2704L14.9991 11.7513L15 11.2322L14.9437 10.9882C14.8126 10.4196 14.5033 9.79109 14.1796 9.43551L14.028 9.26899L13.4772 9.81896Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPetrol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22f17bb elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"22f17bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.20546 0.0446235C2.66851 0.135491 2.17952 0.324998 1.7232 0.619105C1.38661 0.836043 0.883286 1.32113 0.672616 1.63158C-0.224205 2.9531 -0.224205 4.60621 0.672616 5.92773C0.883286 6.23819 1.38661 6.72327 1.7232 6.94021C3.25761 7.92918 5.21106 7.72748 6.50482 6.44652C7.03221 5.92432 7.4006 5.25826 7.55378 4.55001L7.61536 4.26531V3.77966V3.294L7.55378 3.00931C7.26674 1.68209 6.23569 0.559654 4.93895 0.162688C4.41461 0.00215354 3.73147 -0.0443689 3.20546 0.0446235ZM11.6686 2.2353C11.593 2.2693 11.4742 2.36318 11.4046 2.4439C11.252 2.62085 10.4272 4.32078 10.4265 4.45978C10.4263 4.51146 10.4556 4.58297 10.4916 4.6187C10.5277 4.65441 10.9365 4.84248 11.4002 5.03657L12.2432 5.38946L12.3395 5.36849L12.4357 5.34756L12.584 5.11816C12.7577 4.84961 12.9956 4.65126 13.2675 4.54817L13.4619 4.47448L13.9519 4.4513L14.4419 4.42813L14.5479 4.37296C14.6984 4.29459 14.913 4.04118 14.9598 3.8866C15.0181 3.69378 15.0114 2.8837 14.9501 2.71155C14.876 2.50329 14.7434 2.35243 14.5508 2.25734L14.3779 2.17197L13.092 2.1727L11.806 2.17344L11.6686 2.2353ZM1.03796 2.50389L0.958174 2.56786L0.948069 3.43283C0.942493 3.90854 0.946684 4.3323 0.957363 4.3745C0.968042 4.41671 1.0068 4.48098 1.0435 4.51735L1.11025 4.5835H1.9213H2.73235V5.43484C2.73235 5.90308 2.74181 6.3106 2.75334 6.34041C2.77699 6.40147 2.93701 6.49264 3.02051 6.49264C3.05076 6.49264 3.11993 6.44859 3.17427 6.39473L3.27305 6.29683V5.44017V4.5835H3.81375H4.35445V5.44017V6.29683L4.45323 6.39473C4.50757 6.44859 4.57675 6.49264 4.607 6.49264C4.6905 6.49264 4.85051 6.40147 4.87417 6.34041C4.88569 6.3106 4.89516 5.90308 4.89516 5.43484V4.5835H5.70621H6.51726L6.584 4.51735C6.6207 4.48098 6.65946 4.41671 6.67014 4.3745C6.68082 4.3323 6.68501 3.90854 6.67944 3.43283L6.66933 2.56786L6.58955 2.50389C6.4788 2.41506 6.31021 2.42123 6.219 2.51742L6.14553 2.59496V3.32126V4.04761H5.52034H4.89516V3.31658V2.58558L4.81696 2.51273C4.71973 2.42223 4.55786 2.41831 4.45114 2.50389L4.37135 2.56786L4.36108 3.30773L4.3508 4.04761H3.81193H3.27305V3.32599V2.60434L3.19009 2.52214C3.08036 2.41335 2.90649 2.41121 2.80582 2.51742L2.73235 2.59496V3.32126V4.04761H2.10716H1.48198V3.31658V2.58558L1.40378 2.51273C1.30655 2.42223 1.14468 2.41831 1.03796 2.50389ZM10.461 5.46271C10.2876 5.83161 8.70842 9.1189 8.66043 9.21087L8.61001 9.30754L9.27112 9.29842L9.93226 9.28935L10.78 7.51968C11.2562 6.52569 11.615 5.73732 11.5986 5.72108C11.5665 5.68926 10.6138 5.28687 10.5706 5.28687C10.5558 5.28687 10.5065 5.36601 10.461 5.46271ZM4.35412 9.95085C4.29268 9.99231 4.21059 10.0687 4.1717 10.1207L4.101 10.2152L4.0909 11.0277L4.08083 11.8401L4.14696 11.9212L4.21313 12.0023L4.88863 12.0191L5.56414 12.0358L5.63517 12.0996C5.7301 12.1849 5.73199 12.3954 5.63862 12.488L5.57103 12.555H4.26828H2.96556L2.86996 12.604C2.81734 12.6309 2.76489 12.6774 2.75334 12.7072C2.74181 12.737 2.73235 13.2281 2.73235 13.7985V14.8356L2.81531 14.9178L2.89824 15H8.86593H14.8336L14.9166 14.9178L14.9995 14.8356V13.7976V12.7597L14.918 12.6657L14.8365 12.5717L13.4829 12.555L12.1294 12.5382L12.0783 12.4875C12.0502 12.4596 12.0174 12.3887 12.0055 12.3298L11.984 12.2227L12.0867 12.1209L12.1894 12.0191H12.8278H13.4661L13.5384 11.9522C13.6425 11.8561 13.6541 11.7455 13.6418 10.9622L13.6309 10.2607L13.5615 10.1435C13.5233 10.0791 13.4412 9.99248 13.379 9.95095L13.266 9.87549H8.86593H4.46584L4.35412 9.95085Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAutomatic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e809056 e-con-full e-flex e-con e-child\" data-id=\"e809056\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-809b809 elementor-widget elementor-widget-heading\" data-id=\"809b809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">$35,000<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eceeef0 elementor-widget elementor-widget-button\" data-id=\"eceeef0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-cars-single\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><path d=\"M9.72221 0H3.61111C3.45757 0 3.33333 0.124245 3.33333 0.277786C3.33333 0.431328 3.45757 0.555573 3.61111 0.555573H9.05165L0.0813863 9.52586C-0.0271288 9.63436 -0.0271288 9.81014 0.0813863 9.91864C0.135631 9.97286 0.206724 10 0.277792 10C0.34886 10 0.419927 9.97286 0.474198 9.91864L9.44443 0.948357V6.38891C9.44443 6.54245 9.56864 6.66669 9.72221 6.66669C9.87579 6.66669 10 6.54245 10 6.38891V0.277786C10 0.124245 9.87571 0 9.72221 0Z\" fill=\"#EB8A54\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c25206 e-con-full e-flex e-con e-child\" data-id=\"2c25206\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9355fe7 cus_button elementor-widget elementor-widget-button\" data-id=\"9355fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_laptop&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/buy-car\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Explore More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4473e3e e-flex e-con-boxed e-con e-parent\" data-id=\"4473e3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18a17d6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"18a17d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">What our customers say<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6afe3ee e-con-full e-flex e-con e-child\" data-id=\"6afe3ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bee1b7c elementor-pagination-type-progressbar elementor-widget elementor-widget-n-carousel\" data-id=\"bee1b7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;4013404&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;17817cd&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;3832e19&quot;}],&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;pagination&quot;:&quot;progressbar&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c86f6e3 e-flex e-con-boxed e-con e-child\" data-id=\"c86f6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b584f42 e-con-full e-flex e-con e-child\" data-id=\"b584f42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f858734 elementor-widget elementor-widget-image\" data-id=\"f858734\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"454\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-1.jpg\" class=\"attachment-large size-large wp-image-458\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-1.jpg 708w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-1-300x192.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eccdee9 e-con-full e-flex e-con e-child\" data-id=\"eccdee9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dd8131 elementor-widget elementor-widget-text-editor\" data-id=\"8dd8131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Rated 4.7 \/ 5 based on 28,370 reviews Showing our 4 &amp; 5 star reviews<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-783d0ea e-con-full e-flex e-con e-child\" data-id=\"783d0ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29bb806 elementor-widget elementor-widget-icon-box\" data-id=\"29bb806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAli TUFAN\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDesigner\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a45c2d9 elementor-widget elementor-widget-rating\" data-id=\"a45c2d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Rated 5 out of 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de185ef elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"de185ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u201cI had been thinking about selling my car for months but kept delaying it because the process always felt overwhelming.Then I came across Drivlex, and honestly, it changed everything.The platform is incredibly easy to use I uploaded my car details, added a few photos, and within 24 hours I already had multiple interested buyers.&#8221;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d719b2e e-flex e-con-boxed e-con e-child\" data-id=\"d719b2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9ca8fbf e-con-full e-flex e-con e-child\" data-id=\"9ca8fbf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03b32e9 elementor-widget elementor-widget-image\" data-id=\"03b32e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"454\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-2.jpg\" class=\"attachment-large size-large wp-image-468\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-2.jpg 708w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-2-300x192.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecd6c0e e-con-full e-flex e-con e-child\" data-id=\"ecd6c0e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ece5a60 elementor-widget elementor-widget-text-editor\" data-id=\"ece5a60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Rated 4.7 \/ 5 based on 28,370 reviews Showing our 4 &amp; 5 star reviews<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd20877 e-con-full e-flex e-con e-child\" data-id=\"bd20877\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3d26b2 elementor-widget elementor-widget-icon-box\" data-id=\"c3d26b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEmily Rodriguez\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMarketing Manager\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-238198b elementor-widget elementor-widget-rating\" data-id=\"238198b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Rated 5 out of 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5eff66 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"d5eff66\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Drivlex made buying my first car an incredibly smooth experience. The filters helped me narrow down exactly what I wanted.<br \/><br \/>I especially appreciated how clear the car details were no hidden surprises.<br \/><br \/>rom browsing to contacting the seller, everything felt fast and professional. I found my car within two days, and the price was exactly within my budget.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f31f01 e-flex e-con-boxed e-con e-child\" data-id=\"6f31f01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0bd92c7 e-con-full e-flex e-con e-child\" data-id=\"0bd92c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b07e69a elementor-widget elementor-widget-image\" data-id=\"b07e69a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"454\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-3.jpg\" class=\"attachment-large size-large wp-image-472\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-3.jpg 708w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/Client-3-300x192.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40f4e7f e-con-full e-flex e-con e-child\" data-id=\"40f4e7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e62b502 elementor-widget elementor-widget-text-editor\" data-id=\"e62b502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Rated 4.7 \/ 5 based on 28,370 reviews Showing our 4 &amp; 5 star reviews<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab8ff41 e-con-full e-flex e-con e-child\" data-id=\"ab8ff41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbc9792 elementor-widget elementor-widget-icon-box\" data-id=\"dbc9792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDaniel Thompson\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSmall Business Owner\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b352b98 elementor-widget elementor-widget-rating\" data-id=\"b352b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Rated 5 out of 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d83e64 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"4d83e64\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>I\u2019ve used multiple platforms to sell cars before, but Drivlex stands out by far. Listing my vehicle was straightforward,I started receiving genuine inquiries within hours.<\/p><p>What I liked most was the secure messaging system and the guidance on pricing.<\/p><p>The entire process felt safe, organized, and well thought out. I sold my car quicker than expected and at a great price. Drivlex is now my go-to platform.\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fad6738 e-flex e-con-boxed e-con e-parent\" data-id=\"fad6738\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-85cfc8f e-con-full e-flex e-con e-child\" data-id=\"85cfc8f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c0f2aa elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2c0f2aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Do You Want to Sell a Car ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e29836 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1e29836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Discover thousands of verified vehicles from trusted sellers, explore detailed specs, compare prices, and find the perfect car that matches your lifestyle. With Drivlex, buying your next ride is simple, secure, and stress-free.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-190aec5 cus_button elementor-widget elementor-widget-button\" data-id=\"190aec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/drivlex\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact Us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-531c3f0 e-flex e-con-boxed e-con e-parent\" data-id=\"531c3f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53a2264 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"53a2264\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Latest Blog Posts<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a55e2c e-con-full e-flex e-con e-child\" data-id=\"4a55e2c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-427420b elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"427420b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;492&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-492\">.elementor-492 .elementor-element.elementor-element-eabd0f5{--display:flex;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );text-transform:var( --e-global-typography-text-text-transform );font-style:var( --e-global-typography-text-font-style );text-decoration:var( --e-global-typography-text-text-decoration );line-height:var( --e-global-typography-text-line-height );}.elementor-492 .elementor-element.elementor-element-5daaa83 img{width:100%;max-width:100%;border-radius:10px 10px 10px 10px;}.elementor-492 .elementor-element.elementor-element-b954f53{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--justify-content:space-between;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-icon-list .elementor-icon-list-item:not(:last-child):after{border-color:var( --e-global-color-text );}.elementor-widget-icon-list .elementor-icon-list-icon i{color:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-icon svg{fill:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );text-transform:var( --e-global-typography-text-text-transform );font-style:var( --e-global-typography-text-font-style );text-decoration:var( --e-global-typography-text-text-decoration );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-icon-list .elementor-icon-list-text{color:var( --e-global-color-secondary );}.elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-icon i{transition:color 0.3s;}.elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-icon svg{transition:fill 0.3s;}.elementor-492 .elementor-element.elementor-element-2ca62f5{--e-icon-list-icon-size:14px;--icon-vertical-offset:0px;}.elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-item > a{font-family:\"Figtree\", Sans-serif;font-size:14px;font-weight:400;text-transform:none;font-style:normal;text-decoration:none;line-height:1.3em;}.elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-text{color:var( --e-global-color-text );transition:color 0.3s;}.elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-icon i{transition:color 0.3s;}.elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-icon svg{transition:fill 0.3s;}.elementor-492 .elementor-element.elementor-element-792c7d5{--e-icon-list-icon-size:14px;--icon-vertical-offset:0px;}.elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-item > a{font-family:\"Figtree\", Sans-serif;font-size:14px;font-weight:400;text-transform:none;font-style:normal;text-decoration:none;line-height:1.3em;}.elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-text{color:var( --e-global-color-text );transition:color 0.3s;}.elementor-492 .elementor-element.elementor-element-35ddd9d{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );text-transform:var( --e-global-typography-primary-text-transform );font-style:var( --e-global-typography-primary-font-style );text-decoration:var( --e-global-typography-primary-text-decoration );color:var( --e-global-color-primary );}.elementor-492 .elementor-element.elementor-element-09afe02 .elementor-heading-title{font-family:\"Michroma\", Sans-serif;font-size:16px;font-weight:400;text-transform:capitalize;font-style:normal;text-decoration:none;line-height:1.4em;color:var( --e-global-color-text );}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );text-transform:var( --e-global-typography-text-text-transform );font-style:var( --e-global-typography-text-font-style );text-decoration:var( --e-global-typography-text-text-decoration );line-height:var( --e-global-typography-text-line-height );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-492 .elementor-element.elementor-element-e3d2db8{font-family:\"Figtree\", Sans-serif;font-size:18px;font-weight:500;text-transform:none;font-style:normal;text-decoration:none;line-height:1.3em;letter-spacing:0px;width:var( --container-widget-width, 100% );max-width:100%;--container-widget-width:100%;--container-widget-flex-grow:0;}.elementor-492 .elementor-element.elementor-element-e3d2db8 p{margin-block-end:0px;}@media(min-width:768px){.elementor-492 .elementor-element.elementor-element-eabd0f5{--width:100%;}}@media(max-width:1365px) and (min-width:768px){.elementor-492 .elementor-element.elementor-element-eabd0f5{--width:100%;}}@media(max-width:1500px){.elementor-widget-image .widget-image-caption{line-height:var( --e-global-typography-text-line-height );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{line-height:var( --e-global-typography-text-line-height );}.elementor-widget-text-editor{line-height:var( --e-global-typography-text-line-height );}}@media(max-width:1365px){.elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-492 .elementor-element.elementor-element-2ca62f5 .elementor-icon-list-item > a{font-size:13px;}.elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-492 .elementor-element.elementor-element-792c7d5 .elementor-icon-list-item > a{font-size:13px;}.elementor-492 .elementor-element.elementor-element-e3d2db8{font-size:16px;}}@media(max-width:1023px){.elementor-widget-image .widget-image-caption{line-height:var( --e-global-typography-text-line-height );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{line-height:var( --e-global-typography-text-line-height );}.elementor-widget-text-editor{line-height:var( --e-global-typography-text-line-height );}.elementor-492 .elementor-element.elementor-element-e3d2db8{font-size:16px;width:100%;max-width:100%;}}@media(max-width:767px){.elementor-widget-image .widget-image-caption{line-height:var( --e-global-typography-text-line-height );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{line-height:var( --e-global-typography-text-line-height );}.elementor-widget-text-editor{line-height:var( --e-global-typography-text-line-height );}.elementor-492 .elementor-element.elementor-element-e3d2db8{text-align:start;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"492\" class=\"elementor elementor-492 e-loop-item e-loop-item-556 post-556 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eabd0f5 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"eabd0f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5daaa83 elementor-widget elementor-widget-image\" data-id=\"5daaa83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-1-1024x576.jpg\" class=\"attachment-large size-large wp-image-541\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-1-1024x576.jpg 1024w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-1-300x169.jpg 300w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-1-768x432.jpg 768w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-1.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b954f53 e-flex e-con-boxed e-con e-child\" data-id=\"b954f53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca62f5 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2ca62f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Author: sumaiyadev<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-792c7d5 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"792c7d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Date: January 15, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35ddd9d e-flex e-con-boxed e-con e-child\" data-id=\"35ddd9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09afe02 elementor-widget elementor-widget-heading\" data-id=\"09afe02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/wp-4.designtocodes.com\/drivlex\/2026\/01\/15\/10-things-to-check-before-buying-a-used-car\/\">10 Things to Check Before Buying a Used Car<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d2db8 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"e3d2db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAvoid surprises! Here\u2019s what every smart buyer inspects before signing the deal.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"492\" class=\"elementor elementor-492 e-loop-item e-loop-item-554 post-554 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eabd0f5 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"eabd0f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5daaa83 elementor-widget elementor-widget-image\" data-id=\"5daaa83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-2-1024x576.jpg\" class=\"attachment-large size-large wp-image-542\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-2-1024x576.jpg 1024w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-2-300x169.jpg 300w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-2-768x432.jpg 768w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-2.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b954f53 e-flex e-con-boxed e-con e-child\" data-id=\"b954f53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca62f5 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2ca62f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Author: sumaiyadev<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-792c7d5 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"792c7d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Date: January 15, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35ddd9d e-flex e-con-boxed e-con e-child\" data-id=\"35ddd9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09afe02 elementor-widget elementor-widget-heading\" data-id=\"09afe02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/wp-4.designtocodes.com\/drivlex\/2026\/01\/15\/2025-ford-explorer-is-it-worth-the-hype\/\">2025 Ford Explorer \u2013 Is It Worth the Hype?<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d2db8 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"e3d2db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWe break down performance, comfort, and value in Ford\u2019s latest SUV release.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"492\" class=\"elementor elementor-492 e-loop-item e-loop-item-552 post-552 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eabd0f5 e-con-full animated-border-2 e-flex elementor-invisible e-con e-child\" data-id=\"eabd0f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5daaa83 elementor-widget elementor-widget-image\" data-id=\"5daaa83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-3-1024x576.jpg\" class=\"attachment-large size-large wp-image-543\" alt=\"\" srcset=\"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-3-1024x576.jpg 1024w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-3-300x169.jpg 300w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-3-768x432.jpg 768w, https:\/\/wp-4.designtocodes.com\/drivlex\/wp-content\/uploads\/sites\/13\/2026\/01\/post-image-3.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b954f53 e-flex e-con-boxed e-con e-child\" data-id=\"b954f53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca62f5 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2ca62f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Author: sumaiyadev<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-792c7d5 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"792c7d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Date: January 15, 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35ddd9d e-flex e-con-boxed e-con e-child\" data-id=\"35ddd9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09afe02 elementor-widget elementor-widget-heading\" data-id=\"09afe02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/wp-4.designtocodes.com\/drivlex\/2026\/01\/15\/how-to-write-the-perfect-car-listing-description\/\">How to Write the Perfect Car Listing Description<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d2db8 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"e3d2db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLearn how the right words can attract serious buyers fast.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a97eaa e-flex e-con-boxed e-con e-parent\" data-id=\"3a97eaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0622e2a e-con-full e-flex e-con e-child\" data-id=\"0622e2a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7be333 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a7be333\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Questions<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44814a7 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"44814a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Got questions? We\u2019ve got answers. Here\u2019s everything you need to know before buying or selling your car on Drivlex.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c492020 e-con-full e-flex e-con e-child\" data-id=\"c492020\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08f1c11 cus-faq elementor-widget elementor-widget-n-accordion\" data-id=\"08f1c11\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9370\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-9370\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> How do I buy a car on Drivlex? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-9370\" class=\"elementor-element elementor-element-dc0d242 e-con-full faq-content e-flex e-con e-child\" data-id=\"dc0d242\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08c9fdb elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"08c9fdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Simply browse through our listings, filter by model or price, and contact the seller directly through our secure chat system. Once you\u2019re satisfied, schedule an inspection and finalize the deal safely.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9371\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9371\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> How can I sell my car on Drivlex? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-9371\" class=\"elementor-element elementor-element-08bb81b e-con-full faq-content e-flex e-con e-child\" data-id=\"08bb81b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36ba426 elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"36ba426\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Create an account, upload your vehicle details, add photos, set your price, and publish your listing. Drivlex will help you reach thousands of active buyers instantly.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9372\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9372\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Are the car listings verified? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-9372\" class=\"elementor-element elementor-element-7a082e8 e-con-full faq-content e-flex e-con e-child\" data-id=\"7a082e8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2adebf elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b2adebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Yes. Every listing goes through an authenticity check to ensure accurate information, vehicle transparency, and user trust.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9373\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9373\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Do I need to pay to list my car? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-9373\" class=\"elementor-element elementor-element-3fb58de e-con-full faq-content e-flex e-con e-child\" data-id=\"3fb58de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa7b78e elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fa7b78e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Basic listings are free. However, you can choose premium features\u2014like highlighted listings or top placement\u2014to get more visibility.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9374\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9374\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> How does Drivlex keep transactions secure? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-9374\" class=\"elementor-element elementor-element-cc69ba1 e-con-full faq-content e-flex e-con e-child\" data-id=\"cc69ba1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51b96ac elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"51b96ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>We protect user data with strong encryption and provide a secure chat system to prevent unwanted spam, fraud, or fake buyers.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Drive Your Deal Explore thousands of verified car listings or post your own in just a few clicks. Explore Our Collection Verified Buyers Every buyer on Drivlex goes through an authenticity check for safer transactions. Zero Hidden Fees Create your listing for free no commissions or hidden charges. Instant Visibility Your listing reaches thousands of [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":5,"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":991,"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/pages\/9\/revisions\/991"}],"wp:attachment":[{"href":"https:\/\/wp-4.designtocodes.com\/drivlex\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}